{"id":7766,"date":"2025-10-08T17:59:07","date_gmt":"2025-10-08T20:59:07","guid":{"rendered":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg"},"modified":"2025-10-08T17:59:07","modified_gmt":"2025-10-08T20:59:07","slug":"imagem-do-whatsapp-de-2025-10-08-as-17-57-23_a4d32970","status":"inherit","type":"attachment","link":"https:\/\/asfcee.org.br\/index.php\/2025\/09\/30\/parceiro-nova-farma\/imagem-do-whatsapp-de-2025-10-08-as-17-57-23_a4d32970\/","title":{"rendered":"Imagem do WhatsApp de 2025-10-08 \u00e0(s) 17.57.23_a4d32970"},"author":6,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg'><img width=\"240\" height=\"300\" src=\"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-240x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-240x300.jpg 240w, https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-819x1024.jpg 819w, https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-768x960.jpg 768w, https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-1229x1536.jpg 1229w, https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg 1280w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":1600,"file":"2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg","filesize":174219,"sizes":{"medium":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-240x300.jpg","width":240,"height":300,"filesize":16971,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-240x300.jpg"},"large":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-819x1024.jpg","width":819,"height":1024,"filesize":97347,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-819x1024.jpg"},"thumbnail":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-150x150.jpg","width":150,"height":150,"filesize":6648,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-150x150.jpg"},"medium_large":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-768x960.jpg","width":768,"height":960,"filesize":88090,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-768x960.jpg"},"1536x1536":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-1229x1536.jpg","width":1229,"height":1536,"filesize":165553,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-1229x1536.jpg"},"post-thumbnail":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-850x560.jpg","width":850,"height":560,"filesize":56372,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-850x560.jpg"},"digiqole-medium":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-600x398.jpg","width":600,"height":398,"filesize":34947,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-600x398.jpg"},"digiqole-small":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-455x300.jpg","width":455,"height":300,"filesize":23130,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970-455x300.jpg"},"full":{"file":"Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg","width":1280,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7765,"source_url":"https:\/\/asfcee.org.br\/wp-content\/uploads\/2025\/10\/Imagem-do-WhatsApp-de-2025-10-08-as-17.57.23_a4d32970.jpg","_links":{"self":[{"href":"https:\/\/asfcee.org.br\/index.php\/wp-json\/wp\/v2\/media\/7766"}],"collection":[{"href":"https:\/\/asfcee.org.br\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/asfcee.org.br\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/asfcee.org.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/asfcee.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=7766"}]}}